{"id":10236,"date":"2023-10-02T09:09:35","date_gmt":"2023-10-02T07:09:35","guid":{"rendered":"https:\/\/www.safersurfing.org\/loveismore\/?p=10236"},"modified":"2023-10-05T08:04:33","modified_gmt":"2023-10-05T06:04:33","slug":"eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2","status":"publish","type":"post","link":"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/","title":{"rendered":"Eva: &#8222;Mit der Ehe kam die gro\u00dfe Einsamkeit&#8220; (Teil 2)"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><div class=\"fusion-text fusion-text-1\"><\/div>\n<p>In einem ber\u00fchrenden Zeugnis beschreibt Eva* ihren Weg in, durch und aus einer \u00fcberaus schwierigen und verletzenden Ehe (<a href=\"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit\/\">Teil 1<\/a>).<\/p>\n<h2>Pornografie, Drogenkonsum und Betrug<\/h2>\n<p>Auf erstaunliche Weise stolperte ich \u00fcber sein altes Handy und ich konnte nicht glauben, was ich sah. Unmengen an Pornografie, darunter auch homosexuelle Pornografie, Beweise f\u00fcr Drogenkonsum und deren Verkauf (auch bereits vor unserer Hochzeit), Sex-Chats, Belege f\u00fcr eine homosexuelle Beziehung zu seinem Freund, h\u00f6chst abf\u00e4lliges Gerede \u00fcber uns &#8211; ihre Frauen, Beweise f\u00fcr ein Kind mit einer anderen Frau und &#8211; besonders schlimm &#8211; ein vielsagendes Nacktbild von einem sehr jungen M\u00e4dchen.<\/p>\n<blockquote>\n<p>&#8222;Als ich all das sah brachen mein Herz und mein Leben in tausend kleine St\u00fccke. Noch nie zuvor hatte ich einen so tiefen Schmerz gef\u00fchlt. Ich zittere jetzt noch, w\u00e4hrend ich all das aufschreibe und an die Einzelheiten denke. Vieles hat Gott heute geheilt, aber die Wunden und Erinnerungen sind noch immer da.&#8220; (Eva)<\/p>\n<\/blockquote>\n<h2>Ein mutiger Schritt Richtung Freiheit<\/h2>\n<p>Nachdem all dies geschehen war, bat ich Gott um Kraft zur Vergebung und daf\u00fcr, weiterleben zu k\u00f6nnen. Gott war immer und ist auch heute treu. Danach ging alles ganz schnell. Ich wusste, ich konnte nicht bei ihm bleiben und hatte gute Freundinnen, die mich unterst\u00fctzten und mir Mut machten, den n\u00e4chsten Schritt zu tun. Ich ging mit unseren Kindern zu meiner Mutter und wir blieben f\u00fcr einige Wochen.<\/p>\n<p>Er wollte nat\u00fcrlich nicht, dass wir l\u00e4nger blieben. Mir war allerdings klar, dass es zu unserer eigenen Sicherheit war und wir unm\u00f6glich zu ihm zur\u00fcck konnten. Ich hatte so gro\u00dfe Angst, dass er uns holen wollte. Ich habe intensiv nach Hilfe gesucht und habe meinen Mann schlie\u00dflich zu unserem eigenen Schutz verlassen. Es war schwer, ich hatte gro\u00dfe Angst. Ich hatte eine starke Entscheidung getroffen, es gab \u00fcberaus freundliche, hilfsbereite Menschen, die uns sehr geholfen haben.<\/p>\n<blockquote>\n<p>&#8222;All das schreibe ich Gott zu, der sich um uns k\u00fcmmert und damals keinen Augenblick aus den Augen gelassen hat. Er hat uns gesehen und er hat uns nicht vergessen, ihm ist nichts von all dem entgangen und er war mit uns.&#8220; (Eva)<\/p>\n<\/blockquote>\n<h2>Eva: Mit Gott an meiner Seite bin ich stark<\/h2>\n<p>In all diesen Tagen und Wochen f\u00fchlte ich Gott hautnah bei mir und ich wei\u00df, dass er uns besch\u00fctzt und bewahrt hat. Er hat f\u00fcr uns gesorgt und uns gesegnet, wie nur er es kann. Jetzt, wo ich all das niederschreibe, ist schon einige Zeit vergangen und ich danke Gott f\u00fcr seine Hilfe. Es ist immer noch schwierig, aber ich wei\u00df, es wird nicht f\u00fcr immer so bleiben. Ich bin alleine, aber ich f\u00fchle mich nicht so. Es ist nach wie vor eine unglaublich gro\u00dfe Entt\u00e4uschung und es tut immer noch weh, aber etwas hat sich ver\u00e4ndert. In mir.<\/p>\n<p>Jesus ist mein bester Freund und keiner liebt mich so wie er! Er verl\u00e4sst mich nicht. In Ihm finde ich Frieden, Freude, Liebe, Gnade und Hoffnung. Ich wei\u00df, Gott hat einen guten Plan f\u00fcr uns, auch wenn vieles heute noch nicht gut ist und ich mit vielen Schwierigkeiten zu k\u00e4mpfen habe. Ich wei\u00df, die Herausforderungen werden nicht aufh\u00f6ren, doch ich wei\u00df auch, Gott wird immer an meiner Seite sein. Er wird weiterhin auf uns aufpassen, weil er uns liebt und wir ihm wichtig sind. Ich will ihm weiterhin vertrauen!<\/p>\n<h2>Gott liebt den Bund, doch mehr noch den Menschen<\/h2>\n<p>Ein Prediger sagte mir mitten in meiner schwersten Zeit:<\/p>\n<blockquote>\n<p>&#8222;Gott k\u00fcmmert sich mehr um die Menschen in der Ehe als um den Ehebund an sich.&#8220;<\/p>\n<\/blockquote>\n<p>Was meinte er damit? In unserer Gesellschaft leben viele verheiratete Frauen in st\u00e4ndigem Missbrauch. Gleichzeitig sind viele Menschen und auch Prediger der Meinung, dass es niemals akzeptabel sei, sich scheiden zu lassen. Doch dieser Prediger sagte, dass es Gott traurig stimmt, wenn ein Ehemann seine Frau auf irgendeine Weise missbraucht. Oder umgekehrt. Gott liebt jede Person im Ehebund und f\u00fcr ihn ist die Sicherheit des Menschen in der Ehe wichtiger als der Bund selbst.<\/p>\n<p>Niemals wollte ich eine Scheidung. Mein Herzenswunsch war Ehe und Familie. Ich habe lange versucht, meinen Mann zu \u00fcberzeugen, zu \u00fcberreden und meine Grenzen aufzuzeigen.<\/p>\n<blockquote>\n<p>&#8222;Letztlich wurde mir jedoch klar, dass ich aus dieser Ehe ausbrechen musste, um meine Kinder und mich selbst zu sch\u00fctzen.&#8220; (Eva)<\/p>\n<\/blockquote>\n<p>Gott gab mir die Kraft und den Mut ganz allein auf ihn zu vertrauen, denn niemals h\u00e4tte ich es ohne ihn geschafft. Bei ihm sind meine Kinder und ich heute sicher.<\/p>\n<p><a href=\"https:\/\/www.safersurfing.org\/loveismore\/\">Love Is More<\/a> m\u00f6chte Menschen helfen, die direkt oder <a href=\"https:\/\/www.safersurfing.org\/loveismore\/mann-schaut-pornos\/\">indirekt<\/a> unter einer <a href=\"https:\/\/www.safersurfing.org\/loveismore\/hilfe-bei-pornografie-sucht\/\">Pornografieabh\u00e4ngigkeit<\/a> leiden. Bist du oder dein Partner davon betroffen? Auf unserer Website findest du\u00a0<a href=\"https:\/\/www.safersurfing.org\/loveismore\/online-kurse\/\">kostenlose Onlinekurse f\u00fcr Betroffene<\/a>\u00a0und\u00a0<a href=\"https:\/\/www.safersurfing.org\/loveismore\/mann-schaut-pornos\/\">Angebote f\u00fcr Angeh\u00f6rige<\/a>\u00a0sowie Links zu\u00a0<a href=\"https:\/\/www.safersurfing.org\/loveismore\/hilfe-bei-pornografie-sucht\/#shgs_beratung\">Beratungsstellen und Selbsthilfegruppen<\/a>. Teil 1 des Zeugnisses findest du <a href=\"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit\/\">hier<\/a>.<\/p>\n<div ><a class=\"fusion-button button-flat fusion-button-default-size button-default fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/www.safersurfing.org\/loveismore\/mann-schaut-pornos\/#hilfe\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Erste Hilfe!<\/span><\/a><\/div>\n<p>*Name von der Redaktion ge\u00e4ndert<\/p>\n<p>Bildquelle: \u00a9shutterstock\/Matteo Gallina<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In einem ber\u00fchrenden Zeugnis beschreibt Eva* ihren Weg in, durch und aus einer \u00fcberaus schwierigen und verletzenden Ehe.<\/p>\n","protected":false},"author":5,"featured_media":10243,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"footnotes":""},"categories":[178],"tags":[],"class_list":["post-10236","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-parnterinnen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eva - Pornografieabh\u00e4ngigkeit in der Ehe (2)<\/title>\n<meta name=\"description\" content=\"In einem ber\u00fchrenden Zeugnis beschreibt Eva ihren Weg in, durch und aus einer \u00fcberaus schwierigen und verletzenden Ehe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eva: &quot;Mit der Ehe kam die gro\u00dfe Einsamkeit&quot; (Teil 2)\" \/>\n<meta property=\"og:description\" content=\"In einem ber\u00fchrenden Zeugnis beschreibt Eva ihren Weg in, durch und aus einer \u00fcberaus schwierigen und verletzenden Ehe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/\" \/>\n<meta property=\"og:site_name\" content=\"LOVE IS MORE DE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/loveismore.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-02T07:09:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-05T06:04:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.safersurfing.org\/loveismore\/wp-content\/uploads\/sites\/2\/2023\/10\/shutterstock_Matteo-Gallina_800x500.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Katharina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Katharina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/\"},\"author\":{\"name\":\"Katharina\",\"@id\":\"https:\/\/www.safersurfing.org\/loveismore\/#\/schema\/person\/2e7ef85786ff91a4b8a4e6c3363314e1\"},\"headline\":\"Eva: &#8222;Mit der Ehe kam die gro\u00dfe Einsamkeit&#8220; (Teil 2)\",\"datePublished\":\"2023-10-02T07:09:35+00:00\",\"dateModified\":\"2023-10-05T06:04:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/\"},\"wordCount\":1260,\"publisher\":{\"@id\":\"https:\/\/www.safersurfing.org\/loveismore\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.safersurfing.org\/loveismore\/wp-content\/uploads\/sites\/2\/2023\/10\/shutterstock_Matteo-Gallina_800x500.jpg\",\"articleSection\":[\"Hilfe f\u00fcr Partnerinnen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/\",\"url\":\"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/\",\"name\":\"Eva - Pornografieabh\u00e4ngigkeit in der Ehe (2)\",\"isPartOf\":{\"@id\":\"https:\/\/www.safersurfing.org\/loveismore\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.safersurfing.org\/loveismore\/wp-content\/uploads\/sites\/2\/2023\/10\/shutterstock_Matteo-Gallina_800x500.jpg\",\"datePublished\":\"2023-10-02T07:09:35+00:00\",\"dateModified\":\"2023-10-05T06:04:33+00:00\",\"description\":\"In einem ber\u00fchrenden Zeugnis beschreibt Eva ihren Weg in, durch und aus einer \u00fcberaus schwierigen und verletzenden Ehe.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/#primaryimage\",\"url\":\"https:\/\/www.safersurfing.org\/loveismore\/wp-content\/uploads\/sites\/2\/2023\/10\/shutterstock_Matteo-Gallina_800x500.jpg\",\"contentUrl\":\"https:\/\/www.safersurfing.org\/loveismore\/wp-content\/uploads\/sites\/2\/2023\/10\/shutterstock_Matteo-Gallina_800x500.jpg\",\"width\":800,\"height\":500,\"caption\":\"\u00a9shutterstock\/Matteo Gallina\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.safersurfing.org\/loveismore\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eva: &#8222;Mit der Ehe kam die gro\u00dfe Einsamkeit&#8220; (Teil 2)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.safersurfing.org\/loveismore\/#website\",\"url\":\"https:\/\/www.safersurfing.org\/loveismore\/\",\"name\":\"LOVE IS MORE DE\",\"description\":\"Ein Leben ohne Pornografie ist m\u00f6glich\",\"publisher\":{\"@id\":\"https:\/\/www.safersurfing.org\/loveismore\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.safersurfing.org\/loveismore\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.safersurfing.org\/loveismore\/#organization\",\"name\":\"LOVE IS MORE\",\"url\":\"https:\/\/www.safersurfing.org\/loveismore\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.safersurfing.org\/loveismore\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.safersurfing.org\/loveismore\/wp-content\/uploads\/sites\/2\/2018\/06\/Loveismore-Logo-320px.png\",\"contentUrl\":\"https:\/\/www.safersurfing.org\/loveismore\/wp-content\/uploads\/sites\/2\/2018\/06\/Loveismore-Logo-320px.png\",\"width\":320,\"height\":31,\"caption\":\"LOVE IS MORE\"},\"image\":{\"@id\":\"https:\/\/www.safersurfing.org\/loveismore\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/loveismore.org\/\",\"https:\/\/www.youtube.com\/c\/loveismore\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.safersurfing.org\/loveismore\/#\/schema\/person\/2e7ef85786ff91a4b8a4e6c3363314e1\",\"name\":\"Katharina\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eva - Pornografieabh\u00e4ngigkeit in der Ehe (2)","description":"In einem ber\u00fchrenden Zeugnis beschreibt Eva ihren Weg in, durch und aus einer \u00fcberaus schwierigen und verletzenden Ehe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/","og_locale":"de_DE","og_type":"article","og_title":"Eva: \"Mit der Ehe kam die gro\u00dfe Einsamkeit\" (Teil 2)","og_description":"In einem ber\u00fchrenden Zeugnis beschreibt Eva ihren Weg in, durch und aus einer \u00fcberaus schwierigen und verletzenden Ehe.","og_url":"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/","og_site_name":"LOVE IS MORE DE","article_publisher":"https:\/\/www.facebook.com\/loveismore.org\/","article_published_time":"2023-10-02T07:09:35+00:00","article_modified_time":"2023-10-05T06:04:33+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/www.safersurfing.org\/loveismore\/wp-content\/uploads\/sites\/2\/2023\/10\/shutterstock_Matteo-Gallina_800x500.jpg","type":"image\/jpeg"}],"author":"Katharina","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Katharina","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/#article","isPartOf":{"@id":"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/"},"author":{"name":"Katharina","@id":"https:\/\/www.safersurfing.org\/loveismore\/#\/schema\/person\/2e7ef85786ff91a4b8a4e6c3363314e1"},"headline":"Eva: &#8222;Mit der Ehe kam die gro\u00dfe Einsamkeit&#8220; (Teil 2)","datePublished":"2023-10-02T07:09:35+00:00","dateModified":"2023-10-05T06:04:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/"},"wordCount":1260,"publisher":{"@id":"https:\/\/www.safersurfing.org\/loveismore\/#organization"},"image":{"@id":"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.safersurfing.org\/loveismore\/wp-content\/uploads\/sites\/2\/2023\/10\/shutterstock_Matteo-Gallina_800x500.jpg","articleSection":["Hilfe f\u00fcr Partnerinnen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/","url":"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/","name":"Eva - Pornografieabh\u00e4ngigkeit in der Ehe (2)","isPartOf":{"@id":"https:\/\/www.safersurfing.org\/loveismore\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/#primaryimage"},"image":{"@id":"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.safersurfing.org\/loveismore\/wp-content\/uploads\/sites\/2\/2023\/10\/shutterstock_Matteo-Gallina_800x500.jpg","datePublished":"2023-10-02T07:09:35+00:00","dateModified":"2023-10-05T06:04:33+00:00","description":"In einem ber\u00fchrenden Zeugnis beschreibt Eva ihren Weg in, durch und aus einer \u00fcberaus schwierigen und verletzenden Ehe.","breadcrumb":{"@id":"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/#primaryimage","url":"https:\/\/www.safersurfing.org\/loveismore\/wp-content\/uploads\/sites\/2\/2023\/10\/shutterstock_Matteo-Gallina_800x500.jpg","contentUrl":"https:\/\/www.safersurfing.org\/loveismore\/wp-content\/uploads\/sites\/2\/2023\/10\/shutterstock_Matteo-Gallina_800x500.jpg","width":800,"height":500,"caption":"\u00a9shutterstock\/Matteo Gallina"},{"@type":"BreadcrumbList","@id":"https:\/\/www.safersurfing.org\/loveismore\/eva-mit-der-ehe-kam-die-grosse-einsamkeit-teil-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.safersurfing.org\/loveismore\/"},{"@type":"ListItem","position":2,"name":"Eva: &#8222;Mit der Ehe kam die gro\u00dfe Einsamkeit&#8220; (Teil 2)"}]},{"@type":"WebSite","@id":"https:\/\/www.safersurfing.org\/loveismore\/#website","url":"https:\/\/www.safersurfing.org\/loveismore\/","name":"LOVE IS MORE DE","description":"Ein Leben ohne Pornografie ist m\u00f6glich","publisher":{"@id":"https:\/\/www.safersurfing.org\/loveismore\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.safersurfing.org\/loveismore\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.safersurfing.org\/loveismore\/#organization","name":"LOVE IS MORE","url":"https:\/\/www.safersurfing.org\/loveismore\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.safersurfing.org\/loveismore\/#\/schema\/logo\/image\/","url":"https:\/\/www.safersurfing.org\/loveismore\/wp-content\/uploads\/sites\/2\/2018\/06\/Loveismore-Logo-320px.png","contentUrl":"https:\/\/www.safersurfing.org\/loveismore\/wp-content\/uploads\/sites\/2\/2018\/06\/Loveismore-Logo-320px.png","width":320,"height":31,"caption":"LOVE IS MORE"},"image":{"@id":"https:\/\/www.safersurfing.org\/loveismore\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/loveismore.org\/","https:\/\/www.youtube.com\/c\/loveismore"]},{"@type":"Person","@id":"https:\/\/www.safersurfing.org\/loveismore\/#\/schema\/person\/2e7ef85786ff91a4b8a4e6c3363314e1","name":"Katharina"}]}},"_links":{"self":[{"href":"https:\/\/www.safersurfing.org\/loveismore\/wp-json\/wp\/v2\/posts\/10236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.safersurfing.org\/loveismore\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.safersurfing.org\/loveismore\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.safersurfing.org\/loveismore\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.safersurfing.org\/loveismore\/wp-json\/wp\/v2\/comments?post=10236"}],"version-history":[{"count":0,"href":"https:\/\/www.safersurfing.org\/loveismore\/wp-json\/wp\/v2\/posts\/10236\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.safersurfing.org\/loveismore\/wp-json\/wp\/v2\/media\/10243"}],"wp:attachment":[{"href":"https:\/\/www.safersurfing.org\/loveismore\/wp-json\/wp\/v2\/media?parent=10236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.safersurfing.org\/loveismore\/wp-json\/wp\/v2\/categories?post=10236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.safersurfing.org\/loveismore\/wp-json\/wp\/v2\/tags?post=10236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}